{"id":924,"count":78,"description":"","link":"https:\/\/www.withinnigeria.com\/entertainment\/tag\/media-personality\/","name":"Media personality","slug":"media-personality","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Media personality News Archives &#187; ENTERTAINMENT \u2014 WITHIN NIGERIA<\/title>\n<meta name=\"description\" content=\"Latest News updates, photos, videos on Media personality\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.withinnigeria.com\/entertainment\/tag\/media-personality\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Media personality Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.withinnigeria.com\/entertainment\/tag\/media-personality\/\" \/>\n<meta property=\"og:site_name\" content=\"ENTERTAINMENT \u2014 WITHIN NIGERIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@withinnigeria\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/tag\\\/media-personality\\\/\",\"url\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/tag\\\/media-personality\\\/\",\"name\":\"Media personality News Archives &#187; ENTERTAINMENT \u2014 WITHIN NIGERIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/#website\"},\"description\":\"Latest News updates, photos, videos on Media personality\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/tag\\\/media-personality\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/tag\\\/media-personality\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Media personality\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/#website\",\"url\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/\",\"name\":\"ENTERTAINMENT \u2014 WITHIN NIGERIA\",\"description\":\"Latest Nigeria Celebrities and Entertainment News\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/#organization\",\"name\":\"WITHN NIGERIA MEDIA LIMITED\",\"url\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/02\\\/logo-main-x2-use-5.png\",\"contentUrl\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/02\\\/logo-main-x2-use-5.png\",\"width\":390,\"height\":108,\"caption\":\"WITHN NIGERIA MEDIA LIMITED\"},\"image\":{\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/entertainment\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/withinnigeria\",\"https:\\\/\\\/x.com\\\/withinnigeria\",\"https:\\\/\\\/instagram.com\\\/withinnigeria\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/withinnigeria\\\/\",\"https:\\\/\\\/youtube.com\\\/channel\\\/UCo0qw0SqhKNTsQQM48FpdTA\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Media personality News Archives &#187; ENTERTAINMENT \u2014 WITHIN NIGERIA","description":"Latest News updates, photos, videos on Media personality","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.withinnigeria.com\/entertainment\/tag\/media-personality\/","og_locale":"en_US","og_type":"article","og_title":"Media personality Archives","og_url":"https:\/\/www.withinnigeria.com\/entertainment\/tag\/media-personality\/","og_site_name":"ENTERTAINMENT \u2014 WITHIN NIGERIA","twitter_card":"summary_large_image","twitter_site":"@withinnigeria","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.withinnigeria.com\/entertainment\/tag\/media-personality\/","url":"https:\/\/www.withinnigeria.com\/entertainment\/tag\/media-personality\/","name":"Media personality News Archives &#187; ENTERTAINMENT \u2014 WITHIN NIGERIA","isPartOf":{"@id":"https:\/\/www.withinnigeria.com\/entertainment\/#website"},"description":"Latest News updates, photos, videos on Media personality","breadcrumb":{"@id":"https:\/\/www.withinnigeria.com\/entertainment\/tag\/media-personality\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.withinnigeria.com\/entertainment\/tag\/media-personality\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.withinnigeria.com\/entertainment\/"},{"@type":"ListItem","position":2,"name":"Media personality"}]},{"@type":"WebSite","@id":"https:\/\/www.withinnigeria.com\/entertainment\/#website","url":"https:\/\/www.withinnigeria.com\/entertainment\/","name":"ENTERTAINMENT \u2014 WITHIN NIGERIA","description":"Latest Nigeria Celebrities and Entertainment News","publisher":{"@id":"https:\/\/www.withinnigeria.com\/entertainment\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.withinnigeria.com\/entertainment\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.withinnigeria.com\/entertainment\/#organization","name":"WITHN NIGERIA MEDIA LIMITED","url":"https:\/\/www.withinnigeria.com\/entertainment\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.withinnigeria.com\/entertainment\/#\/schema\/logo\/image\/","url":"https:\/\/www.withinnigeria.com\/entertainment\/wp-content\/uploads\/sites\/6\/2021\/02\/logo-main-x2-use-5.png","contentUrl":"https:\/\/www.withinnigeria.com\/entertainment\/wp-content\/uploads\/sites\/6\/2021\/02\/logo-main-x2-use-5.png","width":390,"height":108,"caption":"WITHN NIGERIA MEDIA LIMITED"},"image":{"@id":"https:\/\/www.withinnigeria.com\/entertainment\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/withinnigeria","https:\/\/x.com\/withinnigeria","https:\/\/instagram.com\/withinnigeria","https:\/\/www.linkedin.com\/company\/withinnigeria\/","https:\/\/youtube.com\/channel\/UCo0qw0SqhKNTsQQM48FpdTA\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.withinnigeria.com\/entertainment\/wp-json\/wp\/v2\/tags\/924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.withinnigeria.com\/entertainment\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.withinnigeria.com\/entertainment\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.withinnigeria.com\/entertainment\/wp-json\/wp\/v2\/posts?tags=924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}