{"id":54506,"count":1,"description":"","link":"https:\/\/www.withinnigeria.com\/news\/tag\/military-president\/","name":"Military president","slug":"military-president","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Military president News Archives &#187; NEWS PICKS \u2014 WITHIN NIGERIA<\/title>\n<meta name=\"description\" content=\"Latest News updates, photos, videos on Military president\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.withinnigeria.com\/news\/tag\/military-president\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Military president Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.withinnigeria.com\/news\/tag\/military-president\/\" \/>\n<meta property=\"og:site_name\" content=\"NEWS PICKS \u2014 WITHIN NIGERIA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@withinnigeria\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/tag\\\/military-president\\\/\",\"url\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/tag\\\/military-president\\\/\",\"name\":\"Military president News Archives &#187; NEWS PICKS \u2014 WITHIN NIGERIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/#website\"},\"description\":\"Latest News updates, photos, videos on Military president\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/tag\\\/military-president\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/tag\\\/military-president\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Military president\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/\",\"name\":\"NEWS\",\"description\":\"Latest &amp; Trending Nigeria News, Entertainment, Sports\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/#organization\",\"name\":\"WITHN NIGERIA MEDIA LIMITED\",\"url\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/01\\\/Logo-dark-bg.png\",\"contentUrl\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/01\\\/Logo-dark-bg.png\",\"width\":750,\"height\":500,\"caption\":\"WITHN NIGERIA MEDIA LIMITED\"},\"image\":{\"@id\":\"https:\\\/\\\/www.withinnigeria.com\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/withinnigeria\",\"https:\\\/\\\/x.com\\\/withinnigeria\",\"https:\\\/\\\/www.instagram.com\\\/withinnigeria\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/withinnigeria\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCo0qw0SqhKNTsQQM48FpdTA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Military president News Archives &#187; NEWS PICKS \u2014 WITHIN NIGERIA","description":"Latest News updates, photos, videos on Military president","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.withinnigeria.com\/news\/tag\/military-president\/","og_locale":"en_GB","og_type":"article","og_title":"Military president Archives","og_url":"https:\/\/www.withinnigeria.com\/news\/tag\/military-president\/","og_site_name":"NEWS PICKS \u2014 WITHIN NIGERIA","twitter_card":"summary_large_image","twitter_site":"@withinnigeria","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.withinnigeria.com\/news\/tag\/military-president\/","url":"https:\/\/www.withinnigeria.com\/news\/tag\/military-president\/","name":"Military president News Archives &#187; NEWS PICKS \u2014 WITHIN NIGERIA","isPartOf":{"@id":"https:\/\/www.withinnigeria.com\/news\/#website"},"description":"Latest News updates, photos, videos on Military president","breadcrumb":{"@id":"https:\/\/www.withinnigeria.com\/news\/tag\/military-president\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.withinnigeria.com\/news\/tag\/military-president\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.withinnigeria.com\/news\/"},{"@type":"ListItem","position":2,"name":"Military president"}]},{"@type":"WebSite","@id":"https:\/\/www.withinnigeria.com\/news\/#website","url":"https:\/\/www.withinnigeria.com\/news\/","name":"NEWS","description":"Latest &amp; Trending Nigeria News, Entertainment, Sports","publisher":{"@id":"https:\/\/www.withinnigeria.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.withinnigeria.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.withinnigeria.com\/news\/#organization","name":"WITHN NIGERIA MEDIA LIMITED","url":"https:\/\/www.withinnigeria.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.withinnigeria.com\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.withinnigeria.com\/news\/wp-content\/uploads\/sites\/5\/2021\/01\/Logo-dark-bg.png","contentUrl":"https:\/\/www.withinnigeria.com\/news\/wp-content\/uploads\/sites\/5\/2021\/01\/Logo-dark-bg.png","width":750,"height":500,"caption":"WITHN NIGERIA MEDIA LIMITED"},"image":{"@id":"https:\/\/www.withinnigeria.com\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/withinnigeria","https:\/\/x.com\/withinnigeria","https:\/\/www.instagram.com\/withinnigeria\/","https:\/\/www.linkedin.com\/company\/withinnigeria\/","https:\/\/www.youtube.com\/channel\/UCo0qw0SqhKNTsQQM48FpdTA"]}]}},"_links":{"self":[{"href":"https:\/\/www.withinnigeria.com\/news\/wp-json\/wp\/v2\/tags\/54506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.withinnigeria.com\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.withinnigeria.com\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.withinnigeria.com\/news\/wp-json\/wp\/v2\/posts?tags=54506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}